{"id":11643,"date":"2019-01-07T22:51:30","date_gmt":"2019-01-07T21:51:30","guid":{"rendered":"http:\/\/www.lintelligentdabidjan.info\/news\/?p=11643"},"modified":"2019-01-07T23:19:32","modified_gmt":"2019-01-07T22:19:32","slug":"cote-divoire-le-deploiement-a-abidjan-en-janvier-2019-de-la-tnt-confirme","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/cote-divoire-le-deploiement-a-abidjan-en-janvier-2019-de-la-tnt-confirme\/","title":{"rendered":"C\u00f4te d\u2019Ivoire: le d\u00e9ploiement \u00e0 Abidjan en janvier 2019 de la TNT confirm\u00e9"},"content":{"rendered":"<p><strong>Le si\u00e8ge de la Soci\u00e9t\u00e9 ivoirienne de t\u00e9l\u00e9diffusion a servi de cadre, lundi 7 janvier 2019, \u00e0 une c\u00e9r\u00e9monie de salut aux couleurs en pr\u00e9sence de Assoumany Emmanuel, conseiller technique au minist\u00e8re de la Communication et des M\u00e9dias.<\/strong><!--more--><\/p>\n<p>\u00ab D\u2019ici la fin de ce mois de janvier, il y aura de bonnes nouvelles parce que les choses avancent bien. Mais, je me garde de vous les r\u00e9v\u00e9ler \u00bb, a dit le conseiller du ministre Sidi Tour\u00e9. Il a \u00e9galement encourag\u00e9 la Soci\u00e9t\u00e9 ivoirienne de t\u00e9l\u00e9diffusion pour le travail qu\u2019elle a d\u00e9j\u00e0.<\/p>\n<p>Adama Y\u00e9o, directeur g\u00e9n\u00e9ral de Soci\u00e9t\u00e9 ivoirienne de t\u00e9l\u00e9diffusion, a ajout\u00e9 : \u00ab Nous sommes \u00e0 l\u2019\u00e9tape du d\u00e9ploiement de la T\u00e9l\u00e9vision num\u00e9rique terrestre (TNT) qui doit couvrir toute la C\u00f4te d\u2019Ivoire. Nous allons commencer par Abidjan et r\u00e9gions parce que c\u2019est la zone la plus importante \u00bb.<\/p>\n<p><em><strong>M.O<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le si\u00e8ge de la Soci\u00e9t\u00e9 ivoirienne de t\u00e9l\u00e9diffusion a servi de cadre, lundi 7 janvier 2019, \u00e0 une c\u00e9r\u00e9monie de salut aux couleurs en pr\u00e9sence de Assoumany Emmanuel, conseiller technique au minist\u00e8re de la Communication et des M\u00e9dias.<\/p>\n","protected":false},"author":2,"featured_media":11648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,18,69],"tags":[],"class_list":["post-11643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-economie","category-media"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/11643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=11643"}],"version-history":[{"count":3,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/11643\/revisions"}],"predecessor-version":[{"id":11651,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/11643\/revisions\/11651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/11648"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=11643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=11643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=11643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}