{"id":19791,"date":"2020-03-15T23:32:02","date_gmt":"2020-03-15T22:32:02","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=19791"},"modified":"2020-03-15T23:32:47","modified_gmt":"2020-03-15T22:32:47","slug":"doudou-ndir-chef-de-mission-de-la-cedeao-la-cei-nous-a-donne-des-elements-precis-et-detailles","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/doudou-ndir-chef-de-mission-de-la-cedeao-la-cei-nous-a-donne-des-elements-precis-et-detailles\/","title":{"rendered":"Doudou Ndir chef de mission de la Cedeao :  \u201cLa CEI nous a donn\u00e9 des \u00e9l\u00e9ments pr\u00e9cis et d\u00e9taill\u00e9s\u201d"},"content":{"rendered":"<p><em><strong>Le vendredi 13  mars 2020 la mission d&#8217;\u00e9valuation pr\u00e9-\u00e9lectorale de la CEDEAO conduite par Doudou Ndir a eu une rencontre avec la Commission \u00e9lectorale ind\u00e9pendante  (Cei) au si\u00e8ge de l&#8217;institution \u00e0 Cocody.<\/strong><\/em><\/p>\n<p>Cette rencontre pr\u00e9sid\u00e9e par le 1er Secr\u00e9taire Permanent Adjoint de la Cei Emile Ebrotti\u00e9, a permis de passer en revue les questions relatives au processus \u00e9lectoral. \u00c0 sa sortie d\u2019audience, le Chef de Mission a d\u00e9clar\u00e9 \u00e0 la presse que le sens de leur visite \u00e9tait dict\u00e9 par le contexte \u00e9lectoral en C\u00f4te d\u2019Ivoire. \u00ab  En tant que CEDEAO, il s\u2019agit pour nous de porter une assistance \u00e9lectorale \u00e0 ce pays comme le pr\u00e9voit le Protocole de la CEDEAO \u00bb. Il dit avoir,   au cours de cette mission,  rencontr\u00e9 des Partis politiques de l\u2019opposition en dehors du PDCI &#8220;que nous n\u2019avons pas pu rencontrer .Et tous, ont relev\u00e9 un certain nombre de contestation et de r\u00e9crimination \u00bb. Toutefois, a t-il ajout\u00e9 \u00ab  la CEI nous a donn\u00e9s de bonnes informations, des \u00e9l\u00e9ments pr\u00e9cis, d\u00e9taill\u00e9s que nous utiliserons dans notre rapport\u00bb.<br \/>\n<strong><br \/>\nTAB avec Sercom <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vendredi 13 mars 2020 la mission d&#8217;\u00e9valuation pr\u00e9-\u00e9lectorale de la CEDEAO conduite par Doudou Ndir a eu une rencontre avec la Commission \u00e9lectorale ind\u00e9pendante (Cei) au si\u00e8ge de l&#8217;institution \u00e0 Cocody. Cette rencontre pr\u00e9sid\u00e9e par le 1er Secr\u00e9taire Permanent Adjoint de la Cei Emile Ebrotti\u00e9, a permis de passer en revue les questions relatives [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,17],"tags":[],"class_list":["post-19791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-politique"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/19791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=19791"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/19791\/revisions"}],"predecessor-version":[{"id":19793,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/19791\/revisions\/19793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/19792"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=19791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=19791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=19791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}