{"id":20640,"date":"2020-05-04T23:02:13","date_gmt":"2020-05-04T21:02:13","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=20640"},"modified":"2020-05-04T23:02:13","modified_gmt":"2020-05-04T21:02:13","slug":"covid-19-senat-jeannot-ahoussou-annonce-le-vote-electronique","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/covid-19-senat-jeannot-ahoussou-annonce-le-vote-electronique\/","title":{"rendered":"Covid-19 \u2013S\u00e9nat :Jeannot Ahoussou annonce le vote \u00e9lectronique"},"content":{"rendered":"<p><em><strong>Le ministre de l\u2019\u00c9conomie et des Finances, Adama Coulibaly \u00e9tait le jeudi 30 avril 2020  face aux s\u00e9nateurs pour  les instruire  sur le plan de soutien \u00e9conomique social et humanitaire du gouvernement  face \u00e0 la crise du Covid-19.  Cette s\u00e9ance d\u2019information s\u2019inscrit dans le cadre du contr\u00f4le de l\u2019action gouvernementale \u00e0 travers l\u2019\u00e9valuation des politiques publiques tel que d\u00e9fini par l\u2019article 93 de la Constitution.<\/strong><\/em><\/p>\n<p>Dans  son discours  introductif, le pr\u00e9sident du S\u00e9nat de C\u00f4te d\u2019Ivoire, Jeannot Ahoussou-Kouadio a f\u00e9licit\u00e9 l\u2019ex\u00e9cutif ivoirien  pour toutes les mesures importantes et n\u00e9cessaires prises pour  faire face \u00e0 cette crise. \u00ab Le S\u00e9nat salue la pro-activit\u00e9 du gouvernement ayant conduit \u00e0 l\u2019\u00e9laboration de ce plan de soutien \u00e9conomique, social et humanitaire d\u2019un montant de plus d\u2019un milliard de francs Cfa, destin\u00e9 \u00e0 soutenir le secteur priv\u00e9, les Petites et Moyennes Entreprises, le secteur informel ainsi que les couches sociales les plus d\u00e9favoris\u00e9es de notre pays \u00bb, a-t-il dit. Il a exprim\u00e9 \u00e9galement les encouragements du S\u00e9nat au Premier ministre, Amadou Gon Coulibaly et \u00e0 l\u2019ensemble du gouvernement pour tous les efforts d\u00e9ploy\u00e9s sur le terrain en vue de stopper l\u2019avanc\u00e9e de cette terrible pand\u00e9mie. Il a indiqu\u00e9 que son institution  entend prendre toute la place qui est la sienne dans cette lutte contre le Covid-19. \u00ab En plus du don d\u2019un montant de 15 millions au ministre de la Sant\u00e9 et de l\u2019Hygi\u00e8ne publique et de la participation des s\u00e9nateurs aux missions de sensibilisation sur le terrain, les travaux de ce jour doivent \u00e9galement se comprendre de la participation du S\u00e9nat \u00e0 ce combat  (\u2026)  Tous les observateurs nationaux et internationaux peuvent constater, en effet, que la lutte contre le Covid-19 n\u2019a pas mis en veilleuse notre d\u00e9mocratie et le fonctionnement de nos Institutions. Toutefois, il a fallu adapter le fonctionnement de notre Institution \u00e0 l\u2019application des mesures barri\u00e8res \u00e9dict\u00e9es afin d\u2019\u00e9viter la propagation de la maladie \u00bb a-t-il  d\u00e9clar\u00e9 . Aussi, a-t-il annonc\u00e9 les innovations que le S\u00e9nat attend apporter dans son fonctionnement, notamment avec le t\u00e9l\u00e9- travail, mais surtout le digital \u00e0 tous les niveaux.  \u00ab Nous sommes r\u00e9solument engag\u00e9s pour aller au-del\u00e0 du t\u00e9l\u00e9-travail, de la participation via le syst\u00e8me informatique pour envisager le vote \u00e9lectronique qui viendra r\u00e9tablir l\u2019\u00e9quit\u00e9 entre les s\u00e9nateurs et assurer leur participation pleine et enti\u00e8re aux travaux de notre Institution qu\u2019ils soient ici ou ailleurs. Nous devons en d\u00e9finitive exp\u00e9rimenter toutes les solutions, moderniser nos m\u00e9thodes de travail pour assurer la continuit\u00e9 effective et optimale du service public. L\u2019apr\u00e8s Covid 19 nous appelle absolument tous \u00e0 aller au num\u00e9rique \u00bb, a-t-il fait savoir. Par ailleurs,  Il a invit\u00e9 les populations \u00e0 la mobilisation et surtout \u00e0 la discipline. \u00ab Dans un contexte o\u00f9 le directeur g\u00e9n\u00e9ral de l\u2019Organisation Mondiale de la sant\u00e9 (OMS) appelle l\u2019Afrique \u00e0 se pr\u00e9parer au pire, chacun doit jouer sa partition pour d\u00e9jouer ces pronostics pessimistes et alarmistes dans notre pays. (\u2026) nous devons \u00eatre \u00e0 l\u2019avant-garde du sursaut national en vue de briser la pernicieuse cha\u00eene de contamination. Qu\u2019il s\u2019agisse d\u2019appuis en num\u00e9raire ou en nature ou encore de prestations diverses fournies dans le cadre de l\u2019information et de la sensibilisation contre le nouveau coronavirus, aucune contribution ne sera minime, aucune autre ne sera de trop ; chacune vaudra son pesant d\u2019or \u00bb, a-t-il soulign\u00e9. Aussi, il  a exhort\u00e9  les uns et les autres \u00e0 renforcer l\u2019\u00e9lan d\u2019amour et de solidarit\u00e9 entre eux. \u00ab  Nous devons revenir \u00e0 nos valeurs africaines o\u00f9 la primaut\u00e9 est accord\u00e9e \u00e0 la communaut\u00e9 sur l\u2019individu. O\u00f9 le pauvre est assist\u00e9 pudiquement sans que sa dignit\u00e9 et son honneur ne soient \u00e9corn\u00e9s. O\u00f9 le riche, avec humilit\u00e9 et sans ostentation, effectue son devoir d\u2019assistance aux plus d\u00e9munis. O\u00f9 les plus jeunes mettent leur force au service des ain\u00e9s. O\u00f9 les ain\u00e9s mettent leur sagesse au service des plus jeunes. Nous devons retenir l\u2019amour, la solidarit\u00e9 et le partage comme les valeurs fondamentales qui doivent gouverner nos rapports aux autres \u00bb, a-t-il  conseill\u00e9 .<br \/>\n<strong><br \/>\nHarry Diallo \u00e0 Yamoussoukro<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l\u2019\u00c9conomie et des Finances, Adama Coulibaly \u00e9tait le jeudi 30 avril 2020 face aux s\u00e9nateurs pour les instruire sur le plan de soutien \u00e9conomique social et humanitaire du gouvernement face \u00e0 la crise du Covid-19. Cette s\u00e9ance d\u2019information s\u2019inscrit dans le cadre du contr\u00f4le de l\u2019action gouvernementale \u00e0 travers l\u2019\u00e9valuation des politiques [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-20640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-societe"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/20640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=20640"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/20640\/revisions"}],"predecessor-version":[{"id":20641,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/20640\/revisions\/20641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/20591"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=20640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=20640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=20640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}