{"id":25463,"date":"2021-03-24T01:42:27","date_gmt":"2021-03-24T00:42:27","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=25463"},"modified":"2021-03-24T01:42:27","modified_gmt":"2021-03-24T00:42:27","slug":"assane-ouedraogo-secretaire-general-du-mur-jaune-on-espere-que-le-cn-fif-reviendra-sur-sa-decision-pour-notre-grand-bonheur","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/assane-ouedraogo-secretaire-general-du-mur-jaune-on-espere-que-le-cn-fif-reviendra-sur-sa-decision-pour-notre-grand-bonheur\/","title":{"rendered":"Assane Ou\u00e9draogo, secr\u00e9taire g\u00e9n\u00e9ral du \u2018\u2019 Mur Jaune\u2019\u2019 : \u201cOn esp\u00e8re que le CN &#8211; FIF reviendra sur sa d\u00e9cision pour notre grand bonheur \u201d"},"content":{"rendered":"<p><em><strong>Joint le mardi 23 mars 2021 pour r\u00e9agir sur la d\u00e9cision prise par le comit\u00e9 de normalisation de la Fif de faire jouer la ligue 1 \u00e0 huis clos, Assane Ou\u00e9draogo, secr\u00e9taire g\u00e9n\u00e9ral du \u2018\u2019 Mur Jaune\u2019\u2019 a dit esp\u00e9rer que Mariam Dao Gabala et son \u00e9quipe reviendront  sur leurs d\u00e9cisions.<\/strong><\/em><\/p>\n<p>\u2018\u2019Nous avons appris comme tous les sportifs la d\u00e9cision du CN &#8211; FIF de jouer les matches de la ligue 1 \u00e0 huis-clos. Cette d\u00e9cision ne nous fait pas plaisir surtout au niveau du \u2018\u2019Mur Jaune\u2019\u2019 , car  nous  avons profit\u00e9 de la longue tr\u00eave pour effectuer des tourn\u00e9es de mobilisation et de sensibilisation \u00e0 travers certaines villes et aussi des quartiers d&#8217;Abidjan, pour demander aux actionnaires de venir au stade. Nous avons m\u00eame organis\u00e9 les assises du \u2018\u2019Mur Jaune\u201d le 14 Mars pour lancer la nouvelle saison, et voil\u00e0 qu&#8217;une d\u00e9cision vient remettre tout cela  \u00e0 plat. J&#8217;ai le c\u0153ur meurtri pour tous les actionnaires et surtout pour nos joueurs qui seront oblig\u00e9s de jouer sans leurs supporters. On esp\u00e8re que le CN &#8211; FIF reviendra sur sa d\u00e9cision pour notre grand bonheur\u201d, a expliqu\u00e9  Assane Ou\u00e9draogo, secr\u00e9taire g\u00e9n\u00e9ral du \u2018\u2019 Mur Jaune\u2019\u2019 <\/p>\n<p><strong>AK<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joint le mardi 23 mars 2021 pour r\u00e9agir sur la d\u00e9cision prise par le comit\u00e9 de normalisation de la Fif de faire jouer la ligue 1 \u00e0 huis clos, Assane Ou\u00e9draogo, secr\u00e9taire g\u00e9n\u00e9ral du \u2018\u2019 Mur Jaune\u2019\u2019 a dit esp\u00e9rer que Mariam Dao Gabala et son \u00e9quipe reviendront sur leurs d\u00e9cisions. \u2018\u2019Nous avons appris comme [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,23],"tags":[1065,1064,343],"class_list":["post-25463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-sport","tag-assane-ouedraogo","tag-cn","tag-fif"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/25463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=25463"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/25463\/revisions"}],"predecessor-version":[{"id":25465,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/25463\/revisions\/25465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/25464"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=25463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=25463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=25463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}