{"id":30374,"date":"2023-03-24T16:23:34","date_gmt":"2023-03-24T15:23:34","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=30374"},"modified":"2023-03-24T16:32:02","modified_gmt":"2023-03-24T15:32:02","slug":"botro-le-premier-ministre-achi-patrick-lance-les-travaux-du-lycee-professionnel-agricole-de-3653-milliards-de-fcfa","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/botro-le-premier-ministre-achi-patrick-lance-les-travaux-du-lycee-professionnel-agricole-de-3653-milliards-de-fcfa\/","title":{"rendered":"Botro : Le premier Ministre Achi Patrick lance les travaux du lyc\u00e9e professionnel agricole de 3,653 milliards de fcfa"},"content":{"rendered":"<p><em><strong>Le Premier Ministre <a href=\"https:\/\/www.lintelligentdabidjan.info\/news\/lintelligent-en-pdf-remise-dattestation-de-fin-de-formation-aux-metiers-de-mer-a-1000-jeunespatrick-achi-annonce-linsertion-de-660-000-jeunes-entre-2022-et-2024-conflit-rockw\/\" target=\"_blank\">AchiPatrick <\/a>a pr\u00e9sid\u00e9 la C\u00e9r\u00e9monie de lancement des travaux de construction du lyc\u00e9e professionnel sectoriel de formation aux m\u00e9tiers agricoles de Botro. C\u2019\u00e9tait le vendredi 24 mars 2023 en pr\u00e9sence de l\u2019ambassadeur de France en C\u00f4te d\u2019Ivoire, Jean-Christophe Belliard, de plusieurs membres du gouvernement et des \u00e9lus et cadres du d\u00e9partement de Botro dans la r\u00e9gion du Gb\u00eak\u00ea (centre).<\/strong><\/em><\/p>\n<p>Ce lyc\u00e9e sera b\u00e2ti sur une superficie 25 ha et accueillera 350 jeunes pour la formation dipl\u00f4mante et qualifiante aux m\u00e9tiers Agricoles. Inscrit dans le plan national de d\u00e9veloppement (PND 2021-2025) et soutenu par la France \u00e0 travers le contrat de d\u00e9sendettement et de d\u00e9veloppement (C2D) de l\u2019agence fran\u00e7aise de d\u00e9veloppement ( AFD) pour un co\u00fbt global de 3.653.013.903 fcfa, ce projet de formation et d\u2019insertion professionnelle vient r\u00e9sorber le stock de jeunes sans emplois ou mal ins\u00e9r\u00e9s.<\/p>\n<p>C\u2019est une population des Satiklan( peuple baoul\u00e9 de <a href=\"https:\/\/news.lia.ci\/news\/societe\/education-nationale-jules-attingbre-kouame-donne-des-tables-bancs-a-des-villages-de-bodokro\/\" target=\"_blank\">Botro<\/a>) qui est sortie massivement r\u00e9server un accueil chaleureux au premier ministre Achi Patrick et sa d\u00e9l\u00e9gation dans le cadre de la pose de la premi\u00e8re pierre et du lancement des travaux du lyc\u00e9e professionnel sectoriel de formation aux m\u00e9tiers agricoles de Botro.<\/p>\n<p>\u00ab Je suis heureux pour cette mobilisation exceptionnelle \u00e0 Botro. Et je suis encore fier et heureux d\u2019\u00eatre ici pour deux raisons. La premi\u00e8re concerne la jeunesse et la seconde l\u2019agriculture \u00bb a dit Achi Patrick.<\/p>\n<p><strong>Promotion et insertion professionnelle de la jeunesse<\/strong><\/p>\n<p>Le chef du gouvernement justifiant sa premi\u00e8re source de satisfaction d\u2019\u00eatre \u00e0 Botro est revenu sur le programme triennal et l\u2019ann\u00e9e 2023 d\u00e9di\u00e9s \u00e0 la jeunesse. Selon lui, le PJ-Gouv ou programme gouvernemental de la jeunesse a \u00e9t\u00e9 lanc\u00e9 pour donner plus de moyens et d\u2019ambitions aux jeunes, mais et surtout la possibilit\u00e9 d\u2019\u00e9voluer dans un cadre harmonieux qui leur permet de r\u00e9aliser leur r\u00eave.<br \/>\n\u00ab Au cours des trois prochaines ann\u00e9es, ce sont plus de 1.100 milliards de fcfa qui seront investis dans la jeunesse. Pour 2023, c\u2019est 360 milliards de fcfa dont 260 milliards de fcfa pour les activit\u00e9s diverses et 100 milliards de fcfa pour la construction d\u2019infrastructures sp\u00e9cifiques \u00e0 la jeunesse.<br \/>\nA cela vont s\u2019ajouter de nouveaux dispositifs \u00e0 savoir, le vaste programme de service civique avec des centres dans tous les Districts Autonomes du pays, \u00e0 l\u2019image de celui de Bouak\u00e9 que nous allons inaugurer tout \u00e0 l\u2019heure. Il y a aussi l\u2019amplification des programmes d\u2019accompagnement des jeunes dans leur insertion professionnelle \u00e0 travers des activit\u00e9s g\u00e9n\u00e9ratrices de revenus ( AGR) et enfin le financement de micro projets \u00bb a \u00e9gren\u00e9 Patrick Achi.<br \/>\nIl faudra y ajouter les \u00e9coles de la secondes chance pour ceux sortis trop t\u00f4t du syst\u00e8me scolaire.<\/p>\n<p><strong>1 million de jeunes concern\u00e9s en 2023<\/strong><\/p>\n<p>Toujours selon le chef du gouvernement, c\u2019est pr\u00e8s de un million de jeunes qui seront touch\u00e9s par tous ces programmes innovants en 2023 et qui vont s\u2019accentuer en 2024 et 2025.<\/p>\n<p>\u00ab Chers jeunes, c\u2019est cela la C\u00f4te d\u2019Ivoire Solidaire voulue par le pr\u00e9sident Alassane Ouattara, une C\u00f4te d\u2019Ivoire aux c\u00f4t\u00e9s de sa jeunesse, une C\u00f4te d\u2019Ivoire qui pr\u00e9pare l\u2019avenir de ses enfants \u00bb a conclu Achi Patrick.<\/p>\n<p><strong>La deuxi\u00e8me raison de sa joie d\u2019\u00eatre \u00e0 Botro touche l\u2019agriculture <\/strong><\/p>\n<p>Poursuivant sur l\u2019autre raison qui motive, le chef du gouvernement ivoirien a salu\u00e9 la construction de ce lyc\u00e9e agricole qui vient selon lui r\u00e9volutionner le syst\u00e8me agricole en C\u00f4te d\u2019Ivoire.<br \/>\n\u00ab Nous devons d\u00e9velopper encore plus notre agriculture. Et celle d\u2019aujourd\u2019hui n\u2019a rien \u00e0 voir avec celle pratiqu\u00e9e par nos parents avec la daba et le dos courb\u00e9 \u00bb a soulign\u00e9 Achi Patrick.<br \/>\nPour lui, les jeunes qui sortiront de ce lyc\u00e9e seront donc les premiers artisans de cette agriculture nouvelle adapt\u00e9e aux d\u00e9fis nouveaux capable de nourrir la C\u00f4te d\u2019Ivoire et au-del\u00e0 des fronti\u00e8res ivoiriennes.<\/p>\n<p>Enfin le premier ministre a invit\u00e9 les cadres, les chefs traditionnels et les membres du gouvernement originaires de la r\u00e9gion de Gb\u00eak\u00ea \u00e0 l&#8217;union sacr\u00e9e autour des id\u00e9aux de paix, de coh\u00e9sion et de d\u00e9veloppement du pr\u00e9sident Alassane Ouattara.<\/p>\n<p><strong>96% des localit\u00e9s \u00e9lectrifi\u00e9es sous Alassane Ouattara contre 11% avant 2010<\/strong><\/p>\n<p>Avant le premier ministre, le maire de Botro M. Maurice Yao Kouassi a rappel\u00e9 avec \u00e9motion, comment des actes en moins d\u2019une d\u00e9cennie, pos\u00e9s par le pr\u00e9sident Alassane Ouattara ont chang\u00e9 la vie au quotidien des populations de Botro.<br \/>\n\u00ab La construction de ce lyc\u00e9e \u00e9tait une promesse du chef de l\u2019\u00e9tat lors de sa visite d\u2019\u00e9tat le 27 novembre 2013. Aujourd\u2019hui c\u2019est chose faite. Quand le pr\u00e9sident Ouattara dit, il fait \u00bb a dit d\u2019entr\u00e9e le maire. Il a ensuite r\u00e9v\u00e9l\u00e9 que c\u2019est gr\u00e2ce au pr\u00e9sident Alassane Ouattara que Botro est dot\u00e9 d\u2019un ch\u00e2teau d\u2019eau, d\u2019un commissariat, les routes y menant sont bitum\u00e9es. Mieux sur 63 villages du d\u00e9partement, seulement 7 \u00e9taient \u00e9lectrifi\u00e9s entre 1960 et 2010. De 2011 \u00e0 Aujourd\u2019hui il ne reste que 4 villages non \u00e9lectrifi\u00e9s soit un taux d\u2019\u00e9lectrification de 96% \u00e0 mettre \u00e0 l\u2019actif du pr\u00e9sident Alassane Ouattara.<\/p>\n<p><strong>Pr\u00e9sentation du lyc\u00e9e agricole de Botro <\/strong><\/p>\n<p>Le lyc\u00e9e professionnel sectoriel de formation aux m\u00e9tiers agricoles de Botro sera construit sur une superficie de 25 ha dont une zone agricole de 20ha d\u00e9di\u00e9e \u00e0 l\u2019agriculture et \u00e0 l\u2019horticulture, un dortoir de 120 places, une cantine de 200 places, une infirmerie sur une zone b\u00e2tie de 124 M2 pour 3 lits d\u2019observer, une salle de soin et une pharmacie, un ch\u00e2teau d\u2019eau de 10.000 litres, des aires de jeux : football, handball, basket-ball. Il sera livr\u00e9 dans 18 mois.<br \/>\nLes 350 apprenants annuels de niveau CEPE, BEPC, BAC mais aussi les jeunes d\u00e9scolaris\u00e9s, sans qualification y recevront 5 modules de formations . A savoir le mara\u00eechage-culture, la m\u00e9canisation agricole et \u00e9quipement, l\u2019irrigation Drainage Hydraulique agricole, la premi\u00e8re transformation et l\u2019\u00e9levage Pisciculture. Ils sortiront au bout de 3 ans de formation avec un CAP Technique m\u00e9canisation agricole, un CAP technique mara\u00eechage, un BT Premi\u00e8re transformation fermi\u00e8re ou encore un BTS Gestion de syst\u00e8me Irrigu\u00e9.<\/p>\n<p><strong>Philippe Kouhon depuis Botro<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Premier Ministre AchiPatrick a pr\u00e9sid\u00e9 la C\u00e9r\u00e9monie de lancement des travaux de construction du lyc\u00e9e professionnel sectoriel de formation aux m\u00e9tiers agricoles de Botro. C\u2019\u00e9tait le vendredi 24 mars 2023 en pr\u00e9sence de l\u2019ambassadeur de France en C\u00f4te d\u2019Ivoire, Jean-Christophe Belliard, de plusieurs membres du gouvernement et des \u00e9lus et cadres du d\u00e9partement de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,18,3],"tags":[1876,1387,1878,1877],"class_list":["post-30374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-economie","category-societe","tag-achi-patrick","tag-botro","tag-lycee-professionnel-agricole","tag-travaux"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/30374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=30374"}],"version-history":[{"count":3,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/30374\/revisions"}],"predecessor-version":[{"id":30378,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/30374\/revisions\/30378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/30375"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=30374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=30374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=30374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}