{"id":3203,"date":"2017-03-13T08:41:43","date_gmt":"2017-03-13T07:41:43","guid":{"rendered":"http:\/\/www.lintelligentdabidjan.info\/news\/?p=3203"},"modified":"2017-03-13T08:41:43","modified_gmt":"2017-03-13T07:41:43","slug":"adama-toungara-a-la-finale-du-tournoi-de-la-municipalite-je-suis-fier-davoir-une-jeunesse-consciente","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/adama-toungara-a-la-finale-du-tournoi-de-la-municipalite-je-suis-fier-davoir-une-jeunesse-consciente\/","title":{"rendered":"Adama Toungara   \u00e0 la  Finale du Tournoi de la Municipalit\u00e9 :  &#8220;Je suis fier d\u2019avoir une jeunesse consciente&#8221;"},"content":{"rendered":"<p>La 7\u00e8me \u00e9dition du tournoi de football de la Municipalit\u00e9 dot\u00e9 du troph\u00e9e du Maire Adama Toungara, a connu son apoth\u00e9ose, le samedi 11 mars dernier dans l\u2019apr\u00e8s-midi au stade d\u2019Akeikoi extension. <!--more-->En effet, apr\u00e8s deux\u00a0 mois de matches \u00e9liminatoires qui ont mis aux prises seize clubs,\u00a0 FC Abobo T\u00e9 et AC Star Team sont arriv\u00e9s en phase finale. Une finale \u00e2prement disput\u00e9e. Suite au coup d\u2019envoi donn\u00e9,\u00a0 FC Abobo T\u00e9 en maillot rouge blanc et AC Star Team en jaune bleu annoncent les hostilit\u00e9s. Toutes les tentatives de scorer de l\u2019une est contrari\u00e9es par l\u2019autre jusqu\u2019\u00e0 la premi\u00e8re mi-temps. A la reprise, les joueurs de Ac Star Team se font plus mena\u00e7ants, mais leurs offensives buttent sur le solide d\u00e9fense de FC Abobo T\u00e9, qui finit par prendre un but sur un tir bien cadr\u00e9 de Kabor\u00e9 Arouna \u00e0 la 67 mn. Le score restera inchang\u00e9 jusqu\u2019\u00e0 la fin du temps regl\u00e9mentaire.AC Star team remporte le troph\u00e9e Adama Toungara 1-0 au d\u00e9triment de\u00a0 FC Abobo T\u00e9. Initiateur\u00a0 de ce tournoi et pr\u00e9sent \u00e0 la rencontre, le\u00a0 Ministre Adama\u00a0 Toungara a remerci\u00e9 et f\u00e9licit\u00e9 les joueurs pour la qualit\u00e9 du jeu et l\u2019esprit de fair play, qui a pr\u00e9valu tout au long de la comp\u00e9tition, l\u2019encadrement technique pour le coaching des joueurs et le comit\u00e9 d\u2019organisation pour la parfaite organisation de ce tournoi. \u00ab Abobo a fourni les meilleurs joueurs \u00e0 l\u2019\u00e9quipe nationale (&#8230;) Etre Maire de la commune d\u2019Abobo est un honneur et un plaisir. Je suis fier d\u2019avoir une jeunesse consciente. Vous avez vu\u00a0 tout \u00e0 l\u2019heure les jeunes sur le terrain, c\u2019est l\u2019exemple vibrant qu\u2019\u00e0 Abobo, il y a la coh\u00e9sion sociale \u00bb, a dit\u00a0 le premier magistrat de la cit\u00e9, ajoutant que \u00ab Ici \u00e0 Abobo, nous n\u2019essayons pas de nous r\u00e9concilier devant la t\u00e9l\u00e9vision, nous n\u2019essayons pas de faire des choses pour faire plaisir aux autres, mais Abobo, c\u2019est Abobo. Nous sommes totalement int\u00e9gr\u00e9s. Vous n\u2019apprendrez jamais qu\u2019Abobo, qu\u2019il ya des bagarres entre\u00a0 les jeunes de diff\u00e9rentes ethnies ou de\u00a0 diff\u00e9rentes religions, c\u2019est une indication que la politique du Pr\u00e9sident Ouattara de faire de la C\u00f4te d\u2019Ivoire un pays \u00e9mergent, commence, ici, \u00e0 Abobo \u00bb.Pour l\u2019occasion, le Maire avait \u00e0 ses c\u00f4t\u00e9s les honorables D\u00e9put\u00e9s Atto Attebi Alexandre et Kon\u00e9 Siaka, plusieurs de ses collaborateurs et de nombreux jeunes. En match de classement, ASFA a pris le dessus sur ATM aux tirs au but 2-0. L\u2019\u00e9quipe victorieuse du tournoi AC Star Team a re\u00e7u une enveloppe, un troph\u00e9e et de nombreux lots, de m\u00eame\u00a0 que FC Abobo T\u00e9 des mains du Maire. Fofana Mamadou de FC T avec 6 buts, consacr\u00e9 meilleur joueur du tournoi, a \u00e9t\u00e9 r\u00e9compens\u00e9, ainsi que l\u2019\u00e9quipe fair play : AJFA. Plus de 1.300 000 FCFA ont \u00e9t\u00e9 distribu\u00e9s. Ce tournoi dont l\u2019objectif est de rapprocher davantage les jeunes et leur permettre de s\u2019occuper sainement, a vu la participation des anciennes gloires du football ivoirien, \u00e0 savoir Ben Bady, Fadel Keita. Rendez vous est pris pour la 8eme \u00e9dition.<\/p>\n<p>&nbsp;<\/p>\n<p>T.A.B avec Sercom<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 7\u00e8me \u00e9dition du tournoi de football de la Municipalit\u00e9 dot\u00e9 du troph\u00e9e du Maire Adama Toungara, a connu son apoth\u00e9ose, le samedi 11 mars dernier dans l\u2019apr\u00e8s-midi au stade d\u2019Akeikoi extension.<\/p>\n","protected":false},"author":2,"featured_media":3204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-3203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/3203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=3203"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/3203\/revisions"}],"predecessor-version":[{"id":3205,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/3203\/revisions\/3205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/3204"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=3203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=3203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=3203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}