{"id":32469,"date":"2023-11-21T02:04:21","date_gmt":"2023-11-21T01:04:21","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=32469"},"modified":"2023-11-21T02:39:52","modified_gmt":"2023-11-21T01:39:52","slug":"presidentielle-2025-une-ong-veut-digitaliser-les-elections","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/presidentielle-2025-une-ong-veut-digitaliser-les-elections\/","title":{"rendered":"Pr\u00e9sidentielle 2025-Une Ong veut digitaliser les \u00e9lections\u00a0\u00a0"},"content":{"rendered":"<p><em><strong>L \u2019Ong \u00b4\u00b4Tolerance in the world\u2019\u00b4 veut digitaliser l\u2019\u00e9lection pr\u00e9sidentielle de 2025. Elle l\u2019a dit, le samedi 18 novembre 2023 au cours d\u2019une conf\u00e9rence de presse \u00e0 son si\u00e8ge \u00e0 Cocody.<\/strong><\/em><\/p>\n<p>Vianney Koffi, pr\u00e9sident de l\u2019Ong \u00b4\u00b4Tolerance in the world\u2019\u00b4 a r\u00e9v\u00e9l\u00e9 au cours de cette conf\u00e9rence qu\u2019apr\u00e8s des enqu\u00eates relatives \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle de 2010, il a \u00e9t\u00e9 constat\u00e9 que les partisans des candidats Laurent Gbagbo et Alassane Ouattara se plaignaient d&#8217;avoir \u00e9t\u00e9 emp\u00each\u00e9s de voter.<\/p>\n<p>\u00ab Apr\u00e8s les enqu\u00eates sur l\u2019\u00e9lection pr\u00e9sidentielle de 2010, nous nous sommes rendus compte que les \u00e9lecteurs du pr\u00e9sident Laurent Gbagbo et ceux du pr\u00e9sident Alassane Ouattara se plaignaient qu\u2019on les avait emp\u00each\u00e9s de voter tranquillement dans les diff\u00e9rents bureaux de vote. C\u2019est dans ce contexte que nous voulons cr\u00e9er une application digitalis\u00e9e qui permettra de lancer des alertes lors de chaque vote \u00e0 l\u2019aide des Smartphones, au lieu d&#8217;attendre \u00e0 18 h pour remonter les incidents \u00e0 la CEI \u00bb, a laiss\u00e9 entendre Vianney Koffi. Puis, il a ajout\u00e9 qu\u2019\u00e0 travers la digitalisation l\u2019on peut rester chez soi et avoir les r\u00e9sultats. \u00ab \u00c0 travers cette digitalisation, vous pouvez rester chez vous et voter en banque \u00e0 partir de l\u2019Internet, avec un r\u00e9sultat qui sera connu de tous et sans discrimination. En effet, la digitalisation se passera depuis le bureau de vote jusqu\u2019\u00e0 la proclamation des r\u00e9sultats \u00bb, a-t-il pr\u00e9cis\u00e9.\u00a0<\/p>\n<p>Quant \u00e0 Kouam\u00e9 Florent, vice-pr\u00e9sident de l\u2019Ong Tolerance in the world, il a affirm\u00e9 que sa structure dispose d\u2019appareils fiables pour des \u00e9lections sans fraude. \u00ab Nous avons des logiciels appropri\u00e9s avec les partenaires internationaux. Nous implorons l\u2019accord de la CEI et les diff\u00e9rents partis politiques pour qu\u2019ensemble, nous puissions dire non \u00e0 la fraude dans les \u00e9lections \u00e0 venir\u00bb, a soulign\u00e9, le vice-pr\u00e9sident.<\/p>\n<p><strong>Mamadou Ouattara avec B. Aminata (stagiaire)<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L \u2019Ong \u00b4\u00b4Tolerance in the world\u2019\u00b4 veut digitaliser l\u2019\u00e9lection pr\u00e9sidentielle de 2025. Elle l\u2019a dit, le samedi 18 novembre 2023 au cours d\u2019une conf\u00e9rence de presse \u00e0 son si\u00e8ge \u00e0 Cocody. Vianney Koffi, pr\u00e9sident de l\u2019Ong \u00b4\u00b4Tolerance in the world\u2019\u00b4 a r\u00e9v\u00e9l\u00e9 au cours de cette conf\u00e9rence qu\u2019apr\u00e8s des enqu\u00eates relatives \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,17],"tags":[2789,646,1072,1621],"class_list":["post-32469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-politique","tag-digitaliser","tag-elections","tag-ong","tag-presidentielle-2025"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/32469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=32469"}],"version-history":[{"count":3,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/32469\/revisions"}],"predecessor-version":[{"id":32479,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/32469\/revisions\/32479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/32477"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=32469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=32469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=32469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}