{"id":33455,"date":"2024-03-14T02:12:19","date_gmt":"2024-03-14T01:12:19","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=33455"},"modified":"2024-03-14T02:12:30","modified_gmt":"2024-03-14T01:12:30","slug":"universite-de-bouake-emilienne-dakuyo-decroche-son-doctorat-en-sciences-de-gestion","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/universite-de-bouake-emilienne-dakuyo-decroche-son-doctorat-en-sciences-de-gestion\/","title":{"rendered":"Universit\u00e9 de Bouak\u00e9-  \u00c9milienne Dakuyo d\u00e9croche son doctorat en  sciences de gestion"},"content":{"rendered":"<p><em><strong>Les locaux de l\u2019Edhec de Bouak\u00e9 ont abrit\u00e9 le lundi 11 mars 2024, une s\u00e9rie de soutenances de th\u00e8se \u00e0  l\u2019initiative de l\u2019Unit\u00e9 de Formation et de Recherche (Ufr) des Sciences \u00e9conomiques et de gestion de l\u2019Universit\u00e9 Alassane Ouattara (Uao). \u00c9milienne Lingue Dakuyo, a ent\u00e9rin\u00e9 sa th\u00e8se de Doctorat en sciences de gestion avec la mention tr\u00e8s honorable et les f\u00e9licitations du jury.<\/strong><\/em><\/p>\n<p>C\u2019\u00e9tait en pr\u00e9sence du Professeur Ak\u00e9 N&#8217;gbo Gilbert Marie, ex-doyen de la Facult\u00e9 des sciences \u00e9conomiques de l\u2019Universit\u00e9 d\u2019Abidjan-Cocody, et un parterre d\u2019invit\u00e9s constitu\u00e9 de proches et d\u2019amis avec leurs c\u00f4t\u00e9s, le p\u00e8re biologique, Dr Paul Dakuyo, d\u00e9put\u00e9-maire de Bouak\u00e9. L\u2019imp\u00e9trante \u00c9milienne Dakuyo avait pour th\u00e8me de soutenance : &#8221;Notori\u00e9t\u00e9 virtuelle et d\u00e9cision d&#8217;achat en ligne des produits vivriers en C\u00f4te d&#8217;Ivoire : le r\u00f4le de la mention d&#8217;origine g\u00e9ographique&#8221;. Au nom du parrain  Bema Fofana, d\u00e9put\u00e9 de Bouak\u00e9-Commune, sa repr\u00e9sentante N&#8217;guessan Affou\u00e9 Jacqueline a f\u00e9licit\u00e9 les imp\u00e9trantes en particulier \u00c9milienne Dakuyo pour son parcours \u00e9logieux et le th\u00e8me de sa th\u00e8se portant sur la vente des produits vivriers. \u00ab Cette th\u00e8se est certainement une aubaine pour la vente des produits vivriers de nos vaillants producteurs mais aussi une opportunit\u00e9 pour les consommateurs qui peuvent s&#8217;approvisionner en ligne en toute s\u00e9curit\u00e9 \u00bb, a dit N\u2019Guessan Jacqueline.  Dans son expos\u00e9, l\u2019\u00e9tudiante a fait savoir que le choix du th\u00e8me a \u00e9t\u00e9 \u00e9veill\u00e9 par deux motivations principales.  \u00c9milienne Dakuyo explique que le premier est d\u2019ordre subjectif. \u00c0 la fin de la soutenance,  l&#8217;imp\u00e9trante  a \u00e9t\u00e9 jug\u00e9e apte \u00e0 appartenir \u00e0 la soci\u00e9t\u00e9 des savants modernes. \u00ab Le jury apr\u00e8s avoir examin\u00e9 le travail \u00e9crit, apr\u00e8s avoir \u00e9cout\u00e9 la candidate et \u00e9chang\u00e9 avec elle, estime que Mademoiselle \u00c9milienne Lingue Dakuyo est digne d\u2019\u00eatre class\u00e9e au rang de Docteur en sciences de gestion avec la mention tr\u00e8s honorable avec f\u00e9licitations du jury \u00bb, a conclu le Professeur Emmanuel Hounkoucossi, pr\u00e9sident du jury.<\/p>\n<p><strong>Aboubacar Al Syddick \u00e0 Bouak\u00e9<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les locaux de l\u2019Edhec de Bouak\u00e9 ont abrit\u00e9 le lundi 11 mars 2024, une s\u00e9rie de soutenances de th\u00e8se \u00e0 l\u2019initiative de l\u2019Unit\u00e9 de Formation et de Recherche (Ufr) des Sciences \u00e9conomiques et de gestion de l\u2019Universit\u00e9 Alassane Ouattara (Uao). \u00c9milienne Lingue Dakuyo, a ent\u00e9rin\u00e9 sa th\u00e8se de Doctorat en sciences de gestion avec la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,3],"tags":[3251,3250,2030,3252,3249],"class_list":["post-33455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-societe","tag-doctorat","tag-emilienne-dakuyo","tag-gestion","tag-sciences","tag-universite-de-bouake"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=33455"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33455\/revisions"}],"predecessor-version":[{"id":33457,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33455\/revisions\/33457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/33456"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=33455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=33455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=33455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}