{"id":33597,"date":"2024-03-28T02:29:31","date_gmt":"2024-03-28T01:29:31","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=33597"},"modified":"2024-03-28T02:30:40","modified_gmt":"2024-03-28T01:30:40","slug":"daloa-kangah-koffi-reelu-a-la-tete-de-lanaproci","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/daloa-kangah-koffi-reelu-a-la-tete-de-lanaproci\/","title":{"rendered":"Daloa: Kangah Koffi r\u00e9\u00e9lu \u00e0 la t\u00eate de l&#8217;Anaproci"},"content":{"rendered":"<p><em><strong>Kangah Koffi a \u00e9t\u00e9 r\u00e9\u00e9lu pour un mandat de trois ans \u00e0 la t\u00eate de l&#8217;Association Nationale des Producteurs de Caf\u00e9-Cacao de C\u00f4te d&#8217;Ivoire (Anaproci) par les membres du Conseil d&#8217;Administration de ladite association. Cela s&#8217;est d\u00e9roul\u00e9 le mardi 26 mars 2024, lors de l&#8217;Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire de l&#8217;association, \u00e0 laquelle ont particip\u00e9 les d\u00e9l\u00e9gu\u00e9s des 23 r\u00e9gions productrices de caf\u00e9 et de cacao.<\/strong><\/em><\/p>\n<p>Kangah Koffi a aussit\u00f4t d\u00e9voil\u00e9 ses priorit\u00e9s, qui incluent notamment l&#8217;am\u00e9lioration des prix d&#8217;achat aux producteurs et la mise en place de l&#8217;interprofession de la fili\u00e8re, permettant aux producteurs d&#8217;\u00eatre directement impliqu\u00e9s dans son d\u00e9veloppement et sa gestion. Il a exprim\u00e9 la gratitude des producteurs de caf\u00e9-cacao envers le pr\u00e9sident de la R\u00e9publique et son gouvernement pour les efforts consentis en vue d&#8217;am\u00e9liorer les conditions de vie des producteurs.<\/p>\n<p>&#8220;L&#8217;Anaproci est reconnaissante envers le chef de l&#8217;\u00c9tat pour avoir promulgu\u00e9 l&#8217;ordonnance N\u00b0 2011-473 relative aux organisations interprofessionnelles agricoles. Nous esp\u00e9rons que la mise en \u0153uvre de cette plateforme professionnelle sera conforme \u00e0 la vision du chef de l&#8217;\u00c9tat, qui vise une am\u00e9lioration significative de la vie des producteurs de caf\u00e9-cacao et des autres acteurs de la cha\u00eene de valeur&#8221;, a d\u00e9clar\u00e9 le Pr\u00e9sident du Conseil d&#8217;Administration, Kangah Koffi.<\/p>\n<p>\u00c0 l&#8217;issue de l&#8217;Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire, trois r\u00e9solutions ont \u00e9t\u00e9 prises. Concernant la commercialisation, l&#8217;ANAPROCI demande un bilan du syst\u00e8me de commercialisation et une r\u00e9vision des textes pour mieux prot\u00e9ger les producteurs de caf\u00e9 et de cacao. En ce qui concerne la mise en place de l&#8217;interprofession, l&#8217;Assembl\u00e9e G\u00e9n\u00e9rale recommande de respecter la vision du chef de l&#8217;\u00c9tat consign\u00e9e dans l&#8217;ordonnance relative \u00e0 l&#8217;Interprofession, dont la principale mission est de d\u00e9velopper les producteurs et les autres acteurs de la cha\u00eene de valeur. Enfin, concernant la gestion de la fili\u00e8re caf\u00e9-cacao, l&#8217;Assembl\u00e9e G\u00e9n\u00e9rale recommande aux acteurs ayant particip\u00e9 \u00e0 la gestion de la fili\u00e8re de 2001 \u00e0 2008 de faire le bilan de leur exp\u00e9rience et de partager leurs conclusions avec leurs pairs.<\/p>\n<p><strong><br \/>\nBeker<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kangah Koffi a \u00e9t\u00e9 r\u00e9\u00e9lu pour un mandat de trois ans \u00e0 la t\u00eate de l&#8217;Association Nationale des Producteurs de Caf\u00e9-Cacao de C\u00f4te d&#8217;Ivoire (Anaproci) par les membres du Conseil d&#8217;Administration de ladite association. Cela s&#8217;est d\u00e9roul\u00e9 le mardi 26 mars 2024, lors de l&#8217;Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire de l&#8217;association, \u00e0 laquelle ont particip\u00e9 les d\u00e9l\u00e9gu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,18],"tags":[3319,105,3318],"class_list":["post-33597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-economie","tag-anaproci","tag-daloa","tag-kangah-koffi"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=33597"}],"version-history":[{"count":3,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33597\/revisions"}],"predecessor-version":[{"id":33602,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/33597\/revisions\/33602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/33599"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=33597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=33597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=33597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}