{"id":34005,"date":"2024-05-15T03:20:57","date_gmt":"2024-05-15T01:20:57","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=34005"},"modified":"2024-05-15T03:21:31","modified_gmt":"2024-05-15T01:21:31","slug":"presidentielle-2025-celestin-koalla-le-rhdp-a-un-seul-objectif-cest-la-remobilisation-des-militants","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/presidentielle-2025-celestin-koalla-le-rhdp-a-un-seul-objectif-cest-la-remobilisation-des-militants\/","title":{"rendered":"Pr\u00e9sidentielle 2025-C\u00e9lestin Koalla : \u00ab Le Rhdp a un seul objectif, c\u2019est la remobilisation des militants \u00bb"},"content":{"rendered":"<p><em><strong>C\u00e9lestin Koalla estime que le seul objectif du Rhdp pour l\u2019heure est la mobilisation de ses militants.<\/strong><\/em><\/p>\n<p>En marge de la c\u00e9r\u00e9monie de lancement de la grande mobilisation des femmes, organis\u00e9e le dimanche 12 mai 2024 au complexe sportif d\u2019Abidjan-Abobo par l\u2019Union des Femmes du Rassemblement des Houphou\u00e9tistes pour la D\u00e9mocratie et la Paix (Uf-Rhdp),  C\u00e9lestin Koalla a annonc\u00e9 des actions en vue de r\u00e9ussir cette op\u00e9ration.<\/p>\n<p>C\u00e9lestin Koalla conseiller technique du secr\u00e9taire ex\u00e9cutif du RHDP, a indiqu\u00e9 qu\u2019en pr\u00e9lude \u00e0 la grande  tourn\u00e9e nationale annonc\u00e9e par l\u2019 Uf-Rhdp , les secr\u00e9taires d\u00e9partementaux et lui ont mobilis\u00e9 les femmes de Cocody pour apporter leur soutien et leur appui \u00e0 la pr\u00e9sidente Arlette Badou. Pour lui, ce soutien \u00e0 la pr\u00e9sidente Arlette Badou  et aux femmes du Rhdp vise \u00e0 sensibiliser l\u2019ensemble des populations et leur dire que le pr\u00e9sident Ouattara est le candidat naturel pour poursuivre le d\u00e9veloppement \u00e9conomique du pays. \u00ab Dans tous les d\u00e9partements et toutes les r\u00e9gions de C\u00f4te d\u2019Ivoire, le Rhdp a un seul objectif : c\u2019est la remobilisation des militants, des jeunes, des femmes, les personnes de troisi\u00e8me \u00e2ge afin qu\u2019ils puissent dire clairement que le pr\u00e9sident Ouattara est notre candidat naturel en 2025. Au Rhdp, ce n\u2019est pas un sujet d\u2019h\u00e9sitation, ce n\u2019est pas une question. C\u2019est une affaire r\u00e9gl\u00e9e. Il est le candidat du Rhdp en 2025 \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p><strong> Une  victoire \u00e9crasante du pr\u00e9sident Alassane Ouattara  <\/strong><\/p>\n<p>Par ailleurs, C\u00e9lestin Koalla a confi\u00e9 que cette tourn\u00e9e nationale initi\u00e9e par les femmes du Rhdp vise \u00e0 remobiliser les militants du parti en vue de garantir la victoire du pr\u00e9sident Alassane Ouattara. \u00ab Nous allons nous mobiliser partout et aussi dans tous les d\u00e9partements pour que la victoire du pr\u00e9sident Alassane Ouattara soit \u00e9crasante. Et que les uns et les autres, que ce soit la communaut\u00e9 internationale ou dans la sous-r\u00e9gion, comprennent que c\u2019est nous qui souhaitons, c\u2019est nous qui demandons que le pr\u00e9sident Alassane Ouattara soit notre candidat \u00bb, a-t-il affirm\u00e9 .   Avant de r\u00e9lever  qu\u2019au regard  de  la qualit\u00e9 du travail  du  pr\u00e9sident Alassane Ouattara non seulement pour la C\u00f4te d\u2019Ivoire, pour la sous-r\u00e9gion ouest-africaine, mais \u00e9galement pour l\u2019international, sa pr\u00e9sence en tant que pr\u00e9sident de la C\u00f4te d\u2019Ivoire est un gage de s\u00e9r\u00e9nit\u00e9 et  de s\u00e9curit\u00e9.<\/p>\n<p><strong>Tour\u00e9 Abdoulaye avec A. Traor\u00e9<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e9lestin Koalla estime que le seul objectif du Rhdp pour l\u2019heure est la mobilisation de ses militants. En marge de la c\u00e9r\u00e9monie de lancement de la grande mobilisation des femmes, organis\u00e9e le dimanche 12 mai 2024 au complexe sportif d\u2019Abidjan-Abobo par l\u2019Union des Femmes du Rassemblement des Houphou\u00e9tistes pour la D\u00e9mocratie et la Paix (Uf-Rhdp), [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,17],"tags":[3531,1663,2390,1621,3532,144],"class_list":["post-34005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-politique","tag-celestin-koalla","tag-militants","tag-objectif","tag-presidentielle-2025","tag-remobilisation","tag-rhdp"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/34005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=34005"}],"version-history":[{"count":2,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/34005\/revisions"}],"predecessor-version":[{"id":34008,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/34005\/revisions\/34008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/34006"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=34005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=34005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=34005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}