{"id":39880,"date":"2025-08-29T07:16:22","date_gmt":"2025-08-29T05:16:22","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=39880"},"modified":"2025-08-29T07:16:29","modified_gmt":"2025-08-29T05:16:29","slug":"poste-de-cote-divoire-pourquoi-les-envois-postaux-sont-suspendus-vers-les-etats-unis","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/poste-de-cote-divoire-pourquoi-les-envois-postaux-sont-suspendus-vers-les-etats-unis\/","title":{"rendered":"Poste de C\u00f4te d\u2019Ivoire-   Pourquoi  les envois postaux sont suspendus  vers les \u00c9tats-Unis"},"content":{"rendered":"<p><em><strong>Pourquoi la Poste de C\u00f4te d\u2019Ivoire a suspendu  les envois postaux  vers les \u00c9tats-Unis.<\/strong><\/em><\/p>\n<p>La Poste de C\u00f4te d\u2019Ivoire a annonc\u00e9, dans un communiqu\u00e9 publi\u00e9 le  lundi 25 ao\u00fbt 2025 , la suspension du transport des envois postaux \u00e0 destination des \u00c9tats-Unis. Cette d\u00e9cision fait suite \u00e0 une modification majeure de la r\u00e9glementation am\u00e9ricaine sur les importations, pr\u00e9vue pour entrer en vigueur le 29 ao\u00fbt 2025.<\/p>\n<p>Selon l\u2019institution, la mesure est li\u00e9e \u00e0 la suppression de la r\u00e8gle dite de minimis, qui permettait jusque-l\u00e0 d\u2019exon\u00e9rer de droits de douane certains envois de faible valeur. D\u00e9sormais, les transporteurs a\u00e9riens sont contraints de collecter, d\u00e8s l\u2019origine, les droits de douane pour chaque envoi avant de les reverser aux autorit\u00e9s am\u00e9ricaines.<\/p>\n<p>La compagnie Lufthansa Cargo, principal transporteur de la Poste ivoirienne pour les \u00c9tats-Unis, a inform\u00e9 qu\u2019elle n\u2019acceptera plus d\u2019envois de courrier a\u00e9rien vers ce pays \u00e0 compter du 25 ao\u00fbt 2025. Elle invoque l\u2019absence d\u2019acc\u00e8s aux donn\u00e9es d\u00e9taill\u00e9es relatives aux articles et \u00e0 leur valeur, indispensables pour effectuer le d\u00e9douanement conform\u00e9ment aux nouvelles exigences am\u00e9ricaines.<\/p>\n<p>\u00ab Nous travaillons activement avec les acteurs principaux afin de trouver une solution viable nous permettant de reprendre le transport de courrier a\u00e9rien vers les \u00c9tats-Unis \u00bb, pr\u00e9cise le communiqu\u00e9. La Poste de C\u00f4te d\u2019Ivoire s\u2019est par ailleurs excus\u00e9e pour les d\u00e9sagr\u00e9ments que cette situation, ind\u00e9pendante de sa volont\u00e9, pourrait causer \u00e0 ses usagers.<\/p>\n<p>Cette suspension, qui touche les op\u00e9rateurs postaux du monde entier, s\u2019inscrit dans un contexte de durcissement des r\u00e8gles douani\u00e8res am\u00e9ricaines et pourrait avoir un impact significatif sur les \u00e9changes postaux internationaux avec les \u00c9tats-Unis.<\/p>\n<p><strong>Tour\u00e9 Abdoulaye<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi la Poste de C\u00f4te d\u2019Ivoire a suspendu les envois postaux vers les \u00c9tats-Unis. La Poste de C\u00f4te d\u2019Ivoire a annonc\u00e9, dans un communiqu\u00e9 publi\u00e9 le lundi 25 ao\u00fbt 2025 , la suspension du transport des envois postaux \u00e0 destination des \u00c9tats-Unis. Cette d\u00e9cision fait suite \u00e0 une modification majeure de la r\u00e9glementation am\u00e9ricaine sur [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,18],"tags":[6037,113,6036,6038],"class_list":["post-39880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-economie","tag-envois-postaux","tag-etats-unis","tag-poste-de-cote-divoire","tag-suspendus"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/39880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=39880"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/39880\/revisions"}],"predecessor-version":[{"id":39882,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/39880\/revisions\/39882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/39881"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=39880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=39880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=39880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}