{"id":43909,"date":"2026-05-19T08:13:51","date_gmt":"2026-05-19T06:13:51","guid":{"rendered":"https:\/\/www.lintelligentdabidjan.info\/news\/?p=43909"},"modified":"2026-05-19T08:13:51","modified_gmt":"2026-05-19T06:13:51","slug":"cote-divoire-la-pec-ci-plaide-pour-une-cei-veritablement-independante","status":"publish","type":"post","link":"https:\/\/www.lintelligentdabidjan.info\/news\/cote-divoire-la-pec-ci-plaide-pour-une-cei-veritablement-independante\/","title":{"rendered":"C\u00f4te d&#8217;Ivoire:\u00a0La Pec-Ci plaide pour une Cei v\u00e9ritablement ind\u00e9pendante"},"content":{"rendered":"<p><strong>La Plateforme pour l\u2019Engagement Citoyen de C\u00f4te d\u2019Ivoire (Pec-Ci), regroupant 37 organisations de la soci\u00e9t\u00e9 civile, a tenu une conf\u00e9rence de presse, le jeudi 14 mai 2026, \u00e0 son si\u00e8ge \u00e0 Abidjan-Cocody Riviera Abatta, pour analyser l\u2019actualit\u00e9 sociopolitique nationale.<\/strong><\/p>\n<p>Cette premi\u00e8re sortie m\u00e9diatique de l\u2019ann\u00e9e 2026 a permis \u00e0 la Plateforme pour l\u2019Engagement Citoyen de C\u00f4te d\u2019Ivoire (Pec-Ci) de se prononcer sur plusieurs sujets li\u00e9s \u00e0 l\u2019actualit\u00e9 sociopolitique ivoirienne. \u00c0 cette occasion, le pr\u00e9sident du Conseil d\u2019Administration de la Pec-Ci,\u00a0\u00c9brin Yao, a salu\u00e9 la d\u00e9cision du pr\u00e9sident\u00a0Alassane Ouattara\u00a0de dissoudre la Cei, mesure adopt\u00e9e en Conseil des ministres le mercredi 6 mai 2026. Il a qualifi\u00e9 cette d\u00e9cision de \u00ab premi\u00e8re grande d\u00e9cision \u00bb de l\u2019ann\u00e9e 2026. Toutefois, il a soulev\u00e9 des interrogations quant au timing et aux motivations de cette dissolution. \u00ab Pourquoi est-ce maintenant que le gouvernement ivoirien juge opportun de dissoudre la Cei apr\u00e8s tant de sang vers\u00e9 et tant d\u2019\u00e2mes innocentes perdues au cours de chaque \u00e9ch\u00e9ance pr\u00e9sidentielle ? Pourtant, le pouvoir Rhdp n\u2019a cess\u00e9 de faire l\u2019\u00e9loge des performances de cette Cei, dont le professionnalisme avait \u00e9t\u00e9 chaleureusement salu\u00e9 par le porte-parole du gouvernement apr\u00e8s les pr\u00e9sidentielles de 2025 et les l\u00e9gislatives de d\u00e9cembre 2025 \u00bb, a-t-il questionn\u00e9, relevant des contradictions entre cette d\u00e9cision et les appr\u00e9ciations ant\u00e9rieures jug\u00e9es positives sur le fonctionnement de la Cei. La Pec-Ci a estim\u00e9 \u00e9galement que la dissolution de l\u2019institution, sans concertation pr\u00e9alable avec l\u2019opposition et la soci\u00e9t\u00e9 civile, pourrait fragiliser le climat politique. Elle a appel\u00e9 \u00e0 un processus inclusif pour la mise en place d\u2019un nouvel organe \u00e9lectoral. \u00ab\u00a0La Cei qui vient d\u2019\u00eatre dissoute de mani\u00e8re unilat\u00e9rale a \u00e9t\u00e9 le fruit de consensus et de compromis majeurs entre les acteurs politiques. Sa dissolution en l\u2019absence de concertation pr\u00e9alable avec la classe politique de l\u2019opposition et les acteurs importants de la soci\u00e9t\u00e9 civile ivoirienne nous r\u00e9serve\u00a0\u00a0certainement des surprises d\u00e9sagr\u00e9ables pour les futures \u00e9ch\u00e9ances \u00e9lectorales \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Dans la m\u00eame veine,\u00a0\u00c9brin Yao\u00a0a critiqu\u00e9 la nomination de Coulibaly-Kuibiert Ibrahime \u00e0 la t\u00eate du Conseil d\u2019\u00c9tat, appelant \u00e0 davantage de transparence et de l\u00e9gitimit\u00e9 dans les institutions impliqu\u00e9es dans le processus \u00e9lectoral. \u00ab\u00a0Sachant tr\u00e8s bien que la l\u00e9gitimit\u00e9 et la l\u00e9galit\u00e9 de celui-ci ainsi que de son \u00e9quipe ont toujours \u00e9t\u00e9 contest\u00e9es par les partis significatifs de l\u2019opposition ivoirienne et certaines organisations de la soci\u00e9t\u00e9 civile, quelle est la logique de cette nomination ? \u00bb, a-t-il interrog\u00e9, tout en formulant une proposition : \u00ab Confier cette nouvelle institution \u00e0 100 % \u00e0 des membres de la soci\u00e9t\u00e9 civile recrut\u00e9s par appel \u00e0 candidatures, sans la pr\u00e9sence de militants de partis politiques. En outre, que cette nouvelle Cei soit dot\u00e9e d\u2019un budget cons\u00e9quent vot\u00e9 par l\u2019Assembl\u00e9e nationale afin de lui garantir une ind\u00e9pendance totale \u00bb. Intervenant sur les actions du gouvernement,\u00a0\u00c9brin Yaoa traduit sa gratitude au minist\u00e8re d\u2019\u00c9tat, minist\u00e8re de la Fonction publique et de la Modernisation de l\u2019administration, dirig\u00e9 par Anne D\u00e9sir\u00e9e Ouloto, ainsi qu\u2019au minist\u00e8re du Commerce, de l\u2019Industrie et de l\u2019Artisanat, conduit par Ibrahim Kalil Konat\u00e9, pour les profondes r\u00e9formes engag\u00e9es et les actions concr\u00e8tes men\u00e9es. En plus de ces deux minist\u00e8res, la Pec-Ci a encourag\u00e9 le vice-Premier ministre T\u00e9n\u00e9 Birahima Ouattara dans toutes ses initiatives visant \u00e0 rassembler les Ivoiriens autour d\u2019un id\u00e9al commun : faire en sorte que chaque Ivoirien et chaque Ivoirienne se sente mieux chez lui.<\/p>\n<p><strong>Tour\u00e9 Abdoulaye avec A. Traor\u00e9<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Plateforme pour l\u2019Engagement Citoyen de C\u00f4te d\u2019Ivoire (Pec-Ci), regroupant 37 organisations de la soci\u00e9t\u00e9 civile, a tenu une conf\u00e9rence de presse, le jeudi 14 mai 2026, \u00e0 son si\u00e8ge \u00e0 Abidjan-Cocody Riviera Abatta, pour analyser l\u2019actualit\u00e9 sociopolitique nationale. Cette premi\u00e8re sortie m\u00e9diatique de l\u2019ann\u00e9e 2026 a permis \u00e0 la Plateforme pour l\u2019Engagement Citoyen de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,17],"tags":[436,77,8070,8069],"class_list":["post-43909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-politique","tag-cei","tag-cote-divoire","tag-independante","tag-la-pec-ci"],"_links":{"self":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/43909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/comments?post=43909"}],"version-history":[{"count":1,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/43909\/revisions"}],"predecessor-version":[{"id":43911,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/posts\/43909\/revisions\/43911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media\/43910"}],"wp:attachment":[{"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/media?parent=43909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/categories?post=43909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintelligentdabidjan.info\/news\/wp-json\/wp\/v2\/tags?post=43909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}